{"id":42,"date":"2007-12-03T16:40:44","date_gmt":"2007-12-03T14:40:44","guid":{"rendered":"http:\/\/teeweg.de\/blog\/?p=42"},"modified":"2016-01-12T16:22:40","modified_gmt":"2016-01-12T15:22:40","slug":"heimkunft","status":"publish","type":"post","link":"https:\/\/www.teeweg.de\/blog\/heimkunft\/","title":{"rendered":"Heimkunft"},"content":{"rendered":"<div style=\"text-align: center\"><img decoding=\"async\" src=\"http:\/\/teeweg.de\/graphik\/blog\/matsukirche.jpg\" \/><\/div>\n<p>Auf der Rosenmesse in Kronach waren zwei junge Japanerinnen G\u00e4ste bei unserer Vorf\u00fchrung der Teezeremonie. Beide waren sehr verlegen. Eine hatte in der Schule eine Grundeinf\u00fchrung in die Teezeremonie erhalten, sich aber nie wieder damit besch\u00e4ftigt, die andere hatte selbst niemals Tee gemacht, aber ihre Mutter ist Teelehrerin der Omotosenke.<\/p>\n<p>Wir haben uns inzwischen \u00f6fter getroffen und diskutiert. Es war \u00fcberraschend, wie anders und in einer Weise unjapanisch beide dachten. Schlie\u00dflich stellte sich heraus, dass die eine einen Universit\u00e4tsabschlu\u00df in Kyto \u00fcber deutsche Philosophie gemacht hatte und die andere in Deutschland Germanistik studiert.<br \/>\nInzwischen hatten wir intensive Gespr\u00e4che sowohl \u00fcber die deutsche Philosophie als auch \u00fcber Riky\u00fb&#8217;s Lehrgedichte.<br \/>\n\u00dcber Riky\u00fb&#8217;s Testament sagte die Philosophin: &#8222;Ich kann den Text lesen, aber ich verstehe kein Wort!&#8220;<\/p>\n<p>Weil die Eltern der Philosophin zu Besuch kommen wollten, haben wir intensiv Teezeremonie ge\u00fcbt.<\/p>\n<p>An diesem Wochenende waren die Eltern hier im Myoshinan D\u00f4jo.<br \/>\nWir haben fr\u00e4nkische Weihnachtsm\u00e4rkte besucht, fr\u00e4nkische Wurst gegessen und fr\u00e4nkisches Bier und Kirschwasser getrunken.<br \/>\nDie Eltern und die Schwester waren \u00fcberrascht. Hier ist es &#8222;japanischer&#8220; als bei ihnen zu Hause. Als wir dann im Teeraum den Tee bereiteten, war die Mutter v\u00f6llig verdutzt, als ihre Tochter, die sich in Japan niemals f\u00fcr japanische Kultur interessiert hatte, den Platz wechselte und recht perfekt, wenn auch ein wenig aufgeregt den Tee f\u00fcr ihre Eltern bereitete.<\/p>\n<p>Muss man erst die Heimat verlassen, um die eigenen Wurzeln und die eigene Kultur zu sehen und zu pflegen? Sollte es so sein, dass der Teeweg erst den Umweg \u00fcber Europa machen m\u00fc\u00dfte, um nach Japan heimzukehren?<\/p>\n<p>Sind wir etwa &#8222;japanischer&#8220; als die Japaner?<br \/>\nNein! Wir wollen und d\u00fcrfen unsere eigenen Wurzeln nicht verlassen und nur &#8222;exotische&#8220; Techniken \u00fcben. Aber vielleicht erm\u00f6glicht uns die Besch\u00e4ftigung mit der fremden Kultur, die Eigene zu sehen und sch\u00e4tzen zu lernen. Finden wir heim, indem wir zun\u00e4chst in der Fremde suchen?!<\/p>\n<p>PS.:<\/p>\n<p>Daisetz Suzuki war Professor an der buddhistischen Otani &#8211; Universit\u00e4t in Ky\u00f4to. Erst, nachdem er lange in Amerika und Europa gelebt hatte, wurde er zum gro\u00dfen Interpreten der japanischen Kultur.<\/p>\n<div class=\"thanks_button_div\" \n                  style=\"float: left; margin-left: 0px;\"><div id=\"thanksButtonDiv_42_1\" style=\"background-image:url(http:\/\/www.teeweg.de\/blog\/wp-content\/plugins\/thanks-you-counter-button\/images\/thanks_large_blue.png); background-repeat:no-repeat; float: left; display: inline;\"\n                onmouseover=\"javascript:thankYouChangeButtonImage('thanksButtonDiv_42_1', true);\" \n                onmouseout=\"javascript:thankYouChangeButtonImage('thanksButtonDiv_42_1', false);\"\n                onclick=\"javascript:thankYouChangeButtonImage('thanksButtonDiv_42_1', false);\" >\n                <input type=\"button\" onclick=\"thankYouButtonClick(42, 'You left &ldquo;Thanks&rdquo; already for this post')\" value=\"Danke 1\"\n                  class=\"thanks_button thanks_large thanks_blue\"\n                  style=\"  font-family: Verdana, Arial, Sans-Serif; font-size: 14px; font-weight: normal;; color:#39b778;\"\n                  id=\"thanksButton_42_1\" title=\"Click to leave &ldquo;Thanks&rdquo; for this post\"\/>\n             <\/div><div id=\"ajax_loader_42_1\" style=\"display:inline;visibility: hidden;\"><img decoding=\"async\" alt=\"ajax loader\" src=\"http:\/\/www.teeweg.de\/blog\/wp-content\/plugins\/thanks-you-counter-button\/images\/ajax-loader.gif\" \/><\/div><\/div><div id=\"wp_fb_like_button\" style=\"margin:5px 5px 5px 0;float:left;height:100px;\"><script src=\"http:\/\/connect.facebook.net\/en_US\/all.js#xfbml=1\"><\/script><fb:like href=\"https:\/\/www.teeweg.de\/blog\/heimkunft\/\" send=\"false\" layout=\"standard\" width=\"450\" show_faces=\"false\" font=\"arial\" action=\"like\" colorscheme=\"light\"><\/fb:like><\/div>","protected":false},"excerpt":{"rendered":"<p>Auf der Rosenmesse in Kronach waren zwei junge Japanerinnen G\u00e4ste bei unserer Vorf\u00fchrung der Teezeremonie. Beide waren sehr verlegen. Eine hatte in der Schule eine Grundeinf\u00fchrung in die Teezeremonie erhalten, sich aber nie wieder damit besch\u00e4ftigt, die andere hatte selbst &hellip; <a href=\"https:\/\/www.teeweg.de\/blog\/heimkunft\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":278,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[1,6,2],"tags":[],"class_list":["post-42","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-dichtung-und-philosophie","category-teeweg"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.teeweg.de\/blog\/wp-json\/wp\/v2\/posts\/42","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.teeweg.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.teeweg.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.teeweg.de\/blog\/wp-json\/wp\/v2\/users\/278"}],"replies":[{"embeddable":true,"href":"https:\/\/www.teeweg.de\/blog\/wp-json\/wp\/v2\/comments?post=42"}],"version-history":[{"count":1,"href":"https:\/\/www.teeweg.de\/blog\/wp-json\/wp\/v2\/posts\/42\/revisions"}],"predecessor-version":[{"id":3025,"href":"https:\/\/www.teeweg.de\/blog\/wp-json\/wp\/v2\/posts\/42\/revisions\/3025"}],"wp:attachment":[{"href":"https:\/\/www.teeweg.de\/blog\/wp-json\/wp\/v2\/media?parent=42"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.teeweg.de\/blog\/wp-json\/wp\/v2\/categories?post=42"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.teeweg.de\/blog\/wp-json\/wp\/v2\/tags?post=42"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}